{"id":1558,"date":"2020-08-03T09:52:52","date_gmt":"2020-08-03T12:52:52","guid":{"rendered":"https:\/\/comeca.uy\/?p=1558"},"modified":"2025-04-04T17:07:12","modified_gmt":"2025-04-04T17:07:12","slug":"1-al-7-de-agosto-semana-mundial-de-la-lactancia-materna","status":"publish","type":"post","link":"https:\/\/comeca.uy\/web\/1-al-7-de-agosto-semana-mundial-de-la-lactancia-materna\/","title":{"rendered":"1 al 7 de Agosto &#8211; Semana Mundial de la Lactancia Materna"},"content":{"rendered":"<p>Cada a\u00f1o del 1 al 7 de Agosto se celebra una semana especial, organizada por WABA (Alianza Mundial pro Lactancia Materna), conjuntamente con OMS y UNICEF.<\/p>\n<p><!--more--><\/p>\n<p>El 1\u00ba de Agosto, D\u00cdA MUNDIAL DE LA LACTANCIA MATERNA, se inician acciones para promocionar y proteger la LM y las buenas pr\u00e1cticas de alimentaci\u00f3n.<\/p>\n<p>En este particular 2020, la SMLM se celebra bajo el lema: \u201cApoye la lactancia materna, por un planeta saludable\u201d. Se centra, as\u00ed, en el impacto de la alimentaci\u00f3n infantil sobre el medio ambiente, el cambio clim\u00e1tico y la necesidad urgente de proteger, promover y apoyar la lactancia materna para la salud de las personas y del planeta.<\/p>\n<p>Nos recuerda que \u201cla lactancia materna es un acto natural y ecol\u00f3gico. La leche materna es un recurso renovable, gratuito, que no produce contaminaci\u00f3n ni desperdicio&#8230; \u00a1todo lo contrario! Ayuda a la salud infantil, de la madre y del planeta\u201d.<\/p>\n<p>Debemos recordar que en esta situaci\u00f3n de emergencia mundial debido a la Pandemia por COVID \u2013 19, la evidencia cient\u00edfica apunta a la lactancia materna como un factor protector para la salud de los lactantes e incluso la recomendaci\u00f3n es No interrumpir la LM a\u00fan si la madre padece la enfermedad.<\/p>\n<p>WABA, con su enfoque de cadena c\u00e1lida nos invita a trabajar en todos los sectores y niveles para generar una causa com\u00fan con los grupos activistas en temas ambientales. Juntos, debemos enfatizar el v\u00ednculo entre la lactancia materna y el medio ambiente.<\/p>\n<p>COMECA en el marco de la celebraci\u00f3n de la Semana Mundial de la Lactancia Materna :<\/p>\n<p>COMECA IAMPP, acreditado como HOSPITAL AMIGO DEL NI\u00d1O por UNICEF en el a\u00f1o 1998 y en 2010 por el MSP en la promoci\u00f3n de las BUENAS PR\u00c1CTICAS ALIMENTARIAS del LACTANTE y NI\u00d1O PEQUE\u00d1O.<\/p>\n<p>Cuenta con una pol\u00edtica institucional de acciones de promoci\u00f3n para apoyar la LM y brinda los siguientes servicios:<\/p>\n<p>1. Charlas y talleres de preparaci\u00f3n para el Nacimiento, llevados a cabo por Obstetra Partera &#8211; Asesora en Lactancia Materna (IULAM)- Puericultora, en conjunto con Licenciada en Nutrici\u00f3n, donde se brinda informaci\u00f3n basada en evidencia para el inicio y mantenimiento de la Lactancia Materna a madres, padres y familia.<\/p>\n<p>2. Manual de Lactancia Materna realizado por la Comisi\u00f3n de Lactancia Materna y Buenas Pr\u00e1cticas de Alimentaci\u00f3n del Ni\u00f1o Peque\u00f1o y Lactante de la instituci\u00f3n. Material que COMECA obsequia a las futuras madres en los talleres de lactancia o en las salas de maternidad. Que ha sido actualizado en este a\u00f1o 2020<\/p>\n<p>3. Personal en el sector materno-infantil encargado de brindar apoyo t\u00e9cnico de lactancia, extracci\u00f3n y almacenamiento durante el per\u00edodo postparto.<\/p>\n<p>4. En ambos sanatorios, Obstetras Parteras y Pediatras de guardia 24 hrs para consultas.<\/p>\n<p>5. L\u00ednea telef\u00f3nica especifica, las 24 hs. para evacuar dudas referidas a la lactancia, atendidas por personal especializado.<\/p>\n<p>6. Policl\u00ednicas de lunes a s\u00e1bados con Acceso a Ginecotoc\u00f3logo y\/o Pediatra, con n\u00fameros del d\u00eda.<\/p>\n<p>7. Comisi\u00f3n de Lactancia Materna y Buenas Pr\u00e1cticas de Alimentaci\u00f3n del Ni\u00f1o Peque\u00f1o y Lactante. Que este a\u00f1o cuenta con nueva Presidenta, Dra. Giselle Hontan, y dos nuevas integrantes, Dra. Claudia Cabrera y Dra. Gabriela P\u00e9rez, que se suman al resto del plantel integrado por Lic. en Nutrici\u00f3n Silvana Nu\u00f1ez, Lic. en Enfermer\u00eda Tamara Deluca y Obstetra Partera- Asesora de Lactancia Tamara Videira.<\/p>\n<p>#medicina #salud #pediatr\u00eda #lactancia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cada a\u00f1o del 1 al 7 de Agosto se celebra una semana especial, organizada por WABA (Alianza Mundial pro Lactancia Materna), conjuntamente con OMS y UNICEF.<\/p>\n","protected":false},"author":1,"featured_media":1556,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53,54],"tags":[],"class_list":["post-1558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/comeca.uy\/web\/wp-json\/wp\/v2\/posts\/1558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comeca.uy\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comeca.uy\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comeca.uy\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comeca.uy\/web\/wp-json\/wp\/v2\/comments?post=1558"}],"version-history":[{"count":1,"href":"https:\/\/comeca.uy\/web\/wp-json\/wp\/v2\/posts\/1558\/revisions"}],"predecessor-version":[{"id":3536,"href":"https:\/\/comeca.uy\/web\/wp-json\/wp\/v2\/posts\/1558\/revisions\/3536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comeca.uy\/web\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/comeca.uy\/web\/wp-json\/wp\/v2\/media?parent=1558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comeca.uy\/web\/wp-json\/wp\/v2\/categories?post=1558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comeca.uy\/web\/wp-json\/wp\/v2\/tags?post=1558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}